{"id":222911,"date":"2026-04-14T11:40:41","date_gmt":"2026-04-14T09:40:41","guid":{"rendered":"https:\/\/smartpulser.com\/home\/"},"modified":"2026-05-05T08:23:09","modified_gmt":"2026-05-05T06:23:09","slug":"home","status":"publish","type":"page","link":"https:\/\/soulspiritsaltspa.smartpulser.com\/fr\/","title":{"rendered":"Home"},"content":{"rendered":"<section class=\"et_pb_section_0 et_pb_section et_section_regular et_flex_section\" id=\"home-hero\">\r\n<div class=\"et_pb_row_0 et_pb_row et_flex_row\">\r\n<div class=\"et_pb_column_0 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_tabletWide hero\">\r\n<div class=\"et_pb_code_0 et_pb_code et_pb_module\"><div class=\"et_pb_code_inner\"><div class=\"hero-video\">\n  <!-- Startbild -->\n  <img decoding=\"async\" id=\"startImage\" src=\"\/wp-content\/uploads\/smartpulser_hero_1_start.png\" class=\"hero__image\" alt=\"\">\n\n  <!-- Endbild -->\n  <img decoding=\"async\" id=\"endImage\" src=\"\/wp-content\/uploads\/smartpulser_hero_1_end.png\" class=\"hero__image\"  alt=\"\">\n\n  <!-- Video -->\n  <video id=\"heroVideo\" class=\"hero__video\" muted playsinline preload=\"none\">\n    <source src=\"\/wp-content\/uploads\/smartpulser_hero_2.mp4\" type=\"video\/mp4\">\n  <\/video>\n<\/div><\/div><\/div>\r\n<\/div>\r\n<\/div>\r\n\r\n<div class=\"et_pb_row_1 et_pb_row et_flex_row\">\r\n<div class=\"et_pb_column_1 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_12_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone et_flex_column_12_24_tabletWide\">\r\n<div class=\"et_pb_group_0 et_pb_group et-last-child et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\">\r\n<div class=\"et_pb_image_0 et_pb_image et_pb_module et_flex_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/smartpulser_logo_final_pfade_dark_background.svg\" title=\"smartpulser_logo_final_pfade_dark_background\" class=\"wp-image-15\" \/><\/span><\/div>\r\n\r\n<div class=\"et_pb_heading_0 et_pb_heading et_pb_module et_flex_module headline-gradient\"><div class=\"et_pb_heading_container\"><h1 class=\"et_pb_module_header\">Optimisation totale du corps avec excellence !<\/h1><\/div><\/div>\r\n\r\n<div class=\"et_pb_heading_1 et_pb_heading et_pb_module et_flex_module\"><div class=\"et_pb_heading_container\"><h3 class=\"et_pb_module_header\">D\u00e9couvrez le premier syst\u00e8me PEMF au monde, dot\u00e9 de la technologie r\u00e9volutionnaire \u00ab Inductive Fiber Coil \u00bb et \u00e9quip\u00e9 d'une interface de commande \u00e0 \u00e9cran tactile extr\u00eamement conviviale.<\/h3><\/div><\/div>\r\n<\/div>\r\n<\/div>\r\n\r\n<div class=\"et_pb_column_2 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_12_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone et_flex_column_12_24_tabletWide\">\r\n<div class=\"et_pb_group_1 et_pb_group et-last-child et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough hero-buy-card\">\r\n<div class=\"et_pb_text_0 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\">\u00c0 partir de USD 2.769\n<\/div><\/div>\r\n\r\n<div class=\"et_pb_text_1 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><a class=\"order-button-hero\" href=\"https:\/\/www.swissbionic.com\/shop\/index.php?language=en&amp;rep=\" target=\"_blank\" rel=\"noopener\">Acheter<\/a>\n<\/div><\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/section>\r\n\r\n<section class=\"et_pb_section_1 et_pb_section et_section_regular et_flex_section about\" id=\"gold-standard\">\r\n<div class=\"et_pb_row_2 et_pb_row et_flex_row\">\r\n<div class=\"et_pb_column_3 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_tabletWide\">\r\n<div class=\"et_pb_group_2 et_pb_group et-last-child et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough stacked-header\">\r\n<div class=\"et_pb_heading_2 et_pb_heading et_pb_module et_flex_module\"><div class=\"et_pb_heading_container\"><h2 class=\"et_pb_module_header\">R\u00e9sonance biologique<\/h2><\/div><\/div>\r\n\r\n<div class=\"et_pb_heading_3 et_pb_heading et_pb_module et_flex_module headline-gradient\"><div class=\"et_pb_heading_container\"><h2 class=\"et_pb_module_header\">Le secret du \u00ab moins, c'est plus \u00bb<\/h2><\/div><\/div>\r\n\r\n<div class=\"et_pb_text_2 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p>Le SmartPulser ne se contente pas d'\u00e9mettre de l'\u00e9nergie ; il parle le langage de vos cellules. En nous concentrant sur la gamme des fr\u00e9quences porteuses ultra-basses comprises entre 0,5 et 25 Hz, nous alignons notre technologie sur l'environnement \u00e9lectromagn\u00e9tique naturel de la Terre et les rythmes internes du corps humain.<\/p>\n<\/div><\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n\r\n<div class=\"et_pb_row_3 et_pb_row et_grid_row cards-grid\">\r\n<div class=\"et_pb_column_4 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_animated et-interaction-target-oijjb4hnlx stats-grid\" data-interaction-trigger=\"qmmfiwf6go\" data-interaction-target=\"oijjb4hnlx\">\r\n<div class=\"et_pb_row_4 et_pb_row et_pb_row_nested et_flex_row card-wrap\">\r\n<div class=\"et_pb_column_5 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_tabletWide card\">\r\n<div class=\"et_pb_group_3 et_pb_group et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\" id=\"overlay_unique_id_222922\">\r\n<div class=\"et_pb_image_1 et_pb_image et_pb_module et_flex_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/card_earths_natural_harmony-1.jpg\" title=\"card_earths_natural_harmony-1\" width=\"800\" height=\"450\" srcset=\"https:\/\/smartpulser.com\/wp-content\/uploads\/card_earths_natural_harmony-1.jpg 800w\" sizes=\"(max-width: 800px) 100vw, 800px\" class=\"wp-image-221066\" \/><\/span><\/div>\r\n\r\n<div class=\"et_pb_heading_4 et_pb_heading et_pb_module et_flex_module\"><div class=\"et_pb_heading_container\"><h5 class=\"et_pb_module_header\">L'harmonie naturelle de la Terre<\/h5><\/div><\/div>\r\n\r\n<div class=\"et_pb_text_3 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p>La vie sur Terre a \u00e9volu\u00e9 en harmonie avec les fr\u00e9quences \u00e9lectromagn\u00e9tiques naturelles, souvent d\u00e9crites comme le \u00ab diapason \u00bb de la vie biologique. Le SmartPulser exploite cette gamme de fr\u00e9quences ultra-basses pour \u00e9mettre des signaux biomim\u00e9tiques qui aident \u00e0 ancrer votre corps et \u00e0 le prot\u00e9ger des interf\u00e9rences modernes \u00e0 haute fr\u00e9quence.<\/p>\n<\/div><\/div>\r\n<\/div>\r\n\r\n<div class=\"et_pb_group_4 et_pb_group et-last-child et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\" id=\"overlay_unique_id_222922\">\r\n<div class=\"et_pb_group_5 et_pb_group et-last-child et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\">\r\n<div class=\"et_pb_text_4 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p>En savoir plus<\/p>\n<\/div><\/div>\r\n\r\n<div class=\"et_pb_image_2 et_pb_image et_pb_module et_flex_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/plus-icon-green-white.svg\" title=\"plus-icon-green-white\" class=\"wp-image-220967\" \/><\/span><\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n\r\n<div class=\"et_pb_column_6 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_animated et-interaction-target-o3ztu5s7ws stats-grid\" data-interaction-trigger=\"gas1na35a5\" data-interaction-target=\"o3ztu5s7ws\">\r\n<div class=\"et_pb_row_5 et_pb_row et_pb_row_nested et_flex_row card-wrap\">\r\n<div class=\"et_pb_column_7 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_tabletWide card\">\r\n<div class=\"et_pb_group_6 et_pb_group et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\" id=\"overlay_unique_id_222925\">\r\n<div class=\"et_pb_image_3 et_pb_image et_pb_module et_flex_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/card_the_spectrum_of_vitality-1.jpg\" title=\"card_the_spectrum_of_vitality-1\" width=\"800\" height=\"450\" srcset=\"https:\/\/smartpulser.com\/wp-content\/uploads\/card_the_spectrum_of_vitality-1.jpg 800w\" sizes=\"(max-width: 800px) 100vw, 800px\" class=\"wp-image-221067\" \/><\/span><\/div>\r\n\r\n<div class=\"et_pb_heading_5 et_pb_heading et_pb_module et_flex_module\"><div class=\"et_pb_heading_container\"><h5 class=\"et_pb_module_header\">Le spectre de la vitalit\u00e9<\/h5><\/div><\/div>\r\n\r\n<div class=\"et_pb_text_5 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p>Au sein d\u2019un spectre pr\u00e9cis de fr\u00e9quences naturelles, diff\u00e9rentes gammes sont con\u00e7ues pour favoriser des \u00e9tats cl\u00e9s de bien-\u00eatre, allant de la r\u00e9cup\u00e9ration et de la relaxation profondes \u00e0 la concentration et \u00e0 la vitalit\u00e9. En phase avec les rythmes de votre corps, SmartPulser vous aide \u00e0 passer sans effort du repos \u00e0 l\u2019\u00e9quilibre, puis \u00e0 des performances optimales.<\/p>\n<\/div><\/div>\r\n<\/div>\r\n\r\n<div class=\"et_pb_group_7 et_pb_group et-last-child et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\" id=\"overlay_unique_id_222925\">\r\n<div class=\"et_pb_group_8 et_pb_group et-last-child et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\">\r\n<div class=\"et_pb_text_6 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p>En savoir plus<\/p>\n<\/div><\/div>\r\n\r\n<div class=\"et_pb_image_4 et_pb_image et_pb_module et_flex_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/plus-icon-green-white.svg\" title=\"plus-icon-green-white\" class=\"wp-image-220967\" \/><\/span><\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n\r\n<div class=\"et_pb_column_8 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_animated et-interaction-target-rwv596r2t2 stats-grid\" data-interaction-trigger=\"ywz9em7lsw\" data-interaction-target=\"rwv596r2t2\">\r\n<div class=\"et_pb_row_6 et_pb_row et_pb_row_nested et_flex_row card-wrap\">\r\n<div class=\"et_pb_column_9 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_tabletWide card\">\r\n<div class=\"et_pb_group_9 et_pb_group et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\" id=\"overlay_unique_id_222946\">\r\n<div class=\"et_pb_image_5 et_pb_image et_pb_module et_flex_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/card_why_low_frequency_is_high_impact-1.jpg\" title=\"card_why_low_frequency_is_high_impact-1\" width=\"800\" height=\"450\" srcset=\"https:\/\/smartpulser.com\/wp-content\/uploads\/card_why_low_frequency_is_high_impact-1.jpg 800w\" sizes=\"(max-width: 800px) 100vw, 800px\" class=\"wp-image-221068\" \/><\/span><\/div>\r\n\r\n<div class=\"et_pb_heading_6 et_pb_heading et_pb_module et_flex_module\"><div class=\"et_pb_heading_container\"><h5 class=\"et_pb_module_header\">Pourquoi les basses fr\u00e9quences ont un impact si important<\/h5><\/div><\/div>\r\n\r\n<div class=\"et_pb_text_7 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p>En mati\u00e8re de CEMP holistique, la v\u00e9ritable efficacit\u00e9 r\u00e9side dans la simplicit\u00e9, car moins, c'est mieux. SmartPulser fonctionne exclusivement dans la gamme ELF, douce et sans risque, pour soutenir votre corps par une r\u00e9sonance naturelle au lieu de le submerger de facteurs de stress \u00e0 haute fr\u00e9quence.<\/p>\n<\/div><\/div>\r\n<\/div>\r\n\r\n<div class=\"et_pb_group_10 et_pb_group et-last-child et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\" id=\"overlay_unique_id_222946\">\r\n<div class=\"et_pb_group_11 et_pb_group et-last-child et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\">\r\n<div class=\"et_pb_text_8 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p>En savoir plus<\/p>\n<\/div><\/div>\r\n\r\n<div class=\"et_pb_image_6 et_pb_image et_pb_module et_flex_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/plus-icon-green-white.svg\" title=\"plus-icon-green-white\" class=\"wp-image-220967\" \/><\/span><\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/section>\r\n\r\n<section class=\"et_pb_section_2 et_pb_section et_section_regular et_flex_section\" id=\"home-highlight\">\r\n<div class=\"et_pb_row_7 et_pb_row et_flex_row\">\r\n<div class=\"et_pb_column_10 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_tabletWide\">\r\n<div class=\"et_pb_heading_7 et_pb_heading et_pb_module et_flex_module\"><div class=\"et_pb_heading_container\"><h2 class=\"et_pb_module_header\">La science de l'impulsion<\/h2><\/div><\/div>\r\n\r\n<div class=\"et_pb_heading_8 et_pb_heading et_pb_module et_flex_module headline-gradient\"><div class=\"et_pb_heading_container\"><h2 class=\"et_pb_module_header\">D\u00e9couvrez les points forts<\/h2><\/div><\/div>\r\n<\/div>\r\n<\/div>\r\n\r\n<div class=\"et_pb_row_8 et_pb_row et_flex_row\">\r\n<div class=\"et_pb_column_11 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_tabletWide\">\r\n<div class=\"et_pb_group_carousel_0 et_pb_group_carousel et_pb_group et_pb_module et_pb_group_carousel_arrows_inside et_pb_group_carousel_dots_center et_pb_group_carousel_dots_below et_pb_group_carousel_slides_2\"><div class=\"et_pb_group_carousel_container\"><div class=\"et_pb_group_carousel_track\"><div class=\"et_pb_group_carousel_slide\"><div class=\"et_pb_group_12 et_pb_group et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\">\r\n<div class=\"et_pb_group_13 et_pb_group et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\">\r\n<div class=\"et_pb_heading_9 et_pb_heading et_pb_module et_flex_module\"><div class=\"et_pb_heading_container\"><h4 class=\"et_pb_module_header\">Bobines \u00e0 fibres inductives<\/h4><\/div><\/div>\r\n\r\n<div class=\"et_pb_text_9 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p>La nouvelle g\u00e9n\u00e9ration de diffusion de CEMP.<\/p>\n<\/div><\/div>\r\n<\/div>\r\n\r\n<div class=\"et_pb_row_9 et_pb_row et_pb_row_nested et_flex_row et_clickable\">\r\n<div class=\"et_pb_column_12 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_tabletWide\">\r\n<div class=\"et_pb_group_14 et_pb_group et-last-child et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\">\r\n<div class=\"et_pb_group_15 et_pb_group et-last-child et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\">\r\n<div class=\"et_pb_text_10 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p>En savoir plus<\/p>\n<\/div><\/div>\r\n\r\n<div class=\"et_pb_image_7 et_pb_image et_pb_module et_flex_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/plus-icon-green-white.svg\" title=\"plus-icon-green-white\" class=\"wp-image-220967\" \/><\/span><\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div><\/div><div class=\"et_pb_group_carousel_slide\"><div class=\"et_pb_group_16 et_pb_group et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\">\r\n<div class=\"et_pb_group_17 et_pb_group et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\">\r\n<div class=\"et_pb_heading_10 et_pb_heading et_pb_module et_flex_module\"><div class=\"et_pb_heading_container\"><h4 class=\"et_pb_module_header\">Int\u00e9gration de l'horloge biologique<\/h4><\/div><\/div>\r\n\r\n<div class=\"et_pb_text_11 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p>Synchronisation automatique avec les rythmes naturels de votre corps.<\/p>\n<\/div><\/div>\r\n<\/div>\r\n\r\n<div class=\"et_pb_row_10 et_pb_row et_pb_row_nested et_flex_row et_clickable\">\r\n<div class=\"et_pb_column_13 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_tabletWide\">\r\n<div class=\"et_pb_group_18 et_pb_group et-last-child et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\">\r\n<div class=\"et_pb_group_19 et_pb_group et-last-child et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\">\r\n<div class=\"et_pb_text_12 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p>En savoir plus<\/p>\n<\/div><\/div>\r\n\r\n<div class=\"et_pb_image_8 et_pb_image et_pb_module et_flex_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/plus-icon-green-white.svg\" title=\"plus-icon-green-white\" class=\"wp-image-220967\" \/><\/span><\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div><\/div><div class=\"et_pb_group_carousel_slide\"><div class=\"et_pb_group_20 et_pb_group et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\">\r\n<div class=\"et_pb_group_21 et_pb_group et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\">\r\n<div class=\"et_pb_heading_11 et_pb_heading et_pb_module et_flex_module\"><div class=\"et_pb_heading_container\"><h4 class=\"et_pb_module_header\">L'avantage de la forme d'onde<\/h4><\/div><\/div>\r\n\r\n<div class=\"et_pb_text_13 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p><strong>Triple onde en dents<\/strong> de scie pour une absorption cellulaire maximale dans tout le corps ; <strong>onde carr\u00e9e<\/strong> pour une r\u00e9g\u00e9n\u00e9ration locale cibl\u00e9e.<\/p>\n<\/div><\/div>\r\n<\/div>\r\n\r\n<div class=\"et_pb_row_11 et_pb_row et_pb_row_nested et_flex_row et_clickable\">\r\n<div class=\"et_pb_column_14 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_tabletWide\">\r\n<div class=\"et_pb_group_22 et_pb_group et-last-child et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\">\r\n<div class=\"et_pb_group_23 et_pb_group et-last-child et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\">\r\n<div class=\"et_pb_text_14 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p>En savoir plus<\/p>\n<\/div><\/div>\r\n\r\n<div class=\"et_pb_image_9 et_pb_image et_pb_module et_flex_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/plus-icon-green-white.svg\" title=\"plus-icon-green-white\" class=\"wp-image-220967\" \/><\/span><\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div><\/div><div class=\"et_pb_group_carousel_slide\"><div class=\"et_pb_group_24 et_pb_group et-last-child et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\">\r\n<div class=\"et_pb_group_25 et_pb_group et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\">\r\n<div class=\"et_pb_heading_12 et_pb_heading et_pb_module et_flex_module\"><div class=\"et_pb_heading_container\"><h4 class=\"et_pb_module_header\">Le syst\u00e8me de sommeil SmartPulser<\/h4><\/div><\/div>\r\n\r\n<div class=\"et_pb_text_15 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p>Un sommeil plus intelligent. Un repos plus profond. Un bien-\u00eatre partag\u00e9.<\/p>\n<\/div><\/div>\r\n<\/div>\r\n\r\n<div class=\"et_pb_row_12 et_pb_row et_pb_row_nested et_flex_row et_clickable\">\r\n<div class=\"et_pb_column_15 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_tabletWide\">\r\n<div class=\"et_pb_group_26 et_pb_group et-last-child et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\">\r\n<div class=\"et_pb_group_27 et_pb_group et-last-child et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\">\r\n<div class=\"et_pb_text_16 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p>En savoir plus<\/p>\n<\/div><\/div>\r\n\r\n<div class=\"et_pb_image_10 et_pb_image et_pb_module et_flex_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/plus-icon-green-white.svg\" title=\"plus-icon-green-white\" class=\"wp-image-220967\" \/><\/span><\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div><\/div><\/div><\/div><span class=\"et_pb_group_carousel_arrow et_pb_group_carousel_arrow_prev\" role=\"button\" tabindex=\"0\" aria-label=\"Previous slide\"><span class=\"et-pb-icon\">4<\/span><\/span><span class=\"et_pb_group_carousel_arrow et_pb_group_carousel_arrow_next\" role=\"button\" tabindex=\"0\" aria-label=\"Next slide\"><span class=\"et-pb-icon\">5<\/span><\/span><div class=\"et_pb_group_carousel_dots\"><\/div><\/div>\r\n<\/div>\r\n<\/div>\r\n<\/section>\r\n\r\n<section class=\"et_pb_section_3 et_pb_section et_section_regular et_flex_section\" id=\"home-smartpulser-system\">\r\n<div class=\"et_pb_row_13 et_pb_row et_flex_row stacked\">\r\n<div class=\"et_pb_column_16 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_tabletWide\">\r\n<div class=\"et_pb_group_28 et_pb_group et-last-child et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough stacked-header\">\r\n<div class=\"et_pb_heading_13 et_pb_heading et_pb_module et_flex_module\"><div class=\"et_pb_heading_container\"><h2 class=\"et_pb_module_header\">D\u00e9couvrez-le de plus pr\u00e8s<\/h2><\/div><\/div>\r\n\r\n<div class=\"et_pb_heading_14 et_pb_heading et_pb_module et_flex_module headline-gradient\"><div class=\"et_pb_heading_container\"><h2 class=\"et_pb_module_header\">Le syst\u00e8me SmartPulser<\/h2><\/div><\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n\r\n<div class=\"et_pb_row_14 et_pb_row et_grid_row et_animated cards-grid\">\r\n<div class=\"et_pb_column_17 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et-interaction-target-0uczuz1rus stats-grid\" data-interaction-trigger=\"huwhu347mk\" data-interaction-target=\"0uczuz1rus\">\r\n<div class=\"et_pb_row_15 et_pb_row et_pb_row_nested et_flex_row card-wrap\">\r\n<div class=\"et_pb_column_18 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_tabletWide card\">\r\n<div class=\"et_pb_row_16 et_pb_row et_pb_row_nested et_flex_row\">\r\n<div class=\"et_pb_column_19 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_12_24 et_flex_column_12_24_tablet et_flex_column_24_24_phone et_flex_column_12_24_tabletWide\">\r\n<div class=\"et_pb_image_11 et_pb_image et_pb_module et_flex_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/smartpulser_control_left.png\" title=\"smartpulser_control_left\" width=\"900\" height=\"600\" srcset=\"https:\/\/smartpulser.com\/wp-content\/uploads\/smartpulser_control_left.png 900w, https:\/\/smartpulser.com\/wp-content\/uploads\/smartpulser_control_left-480x320.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 900px, 100vw\" class=\"wp-image-197\" \/><\/span><\/div>\r\n<\/div>\r\n\r\n<div class=\"et_pb_column_20 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_12_24 et_flex_column_12_24_tablet et_flex_column_24_24_phone et_flex_column_12_24_tabletWide\">\r\n<div class=\"et_pb_group_29 et_pb_group et-last-child et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\">\r\n<div class=\"et_pb_heading_15 et_pb_heading et_pb_module et_flex_module\"><div class=\"et_pb_heading_container\"><h3 class=\"et_pb_module_header\">Unit\u00e9 de commande :<\/h3><\/div><\/div>\r\n\r\n<div class=\"et_pb_blurb_0 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_flex_module\"><div class=\"et_pb_blurb_content et_flex_module\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap et_pb_only_image_mode_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/arrow_green.png\" width=\"70\" height=\"70\" srcset=\"https:\/\/smartpulser.com\/wp-content\/uploads\/arrow_green.png 70w\" sizes=\"(max-width: 70px) 100vw, 70px\" class=\"wp-image-223236\" title=\"arrow_green\" \/><\/span><\/div><div class=\"et_pb_blurb_container\"><div class=\"et_pb_blurb_description\"><p><strong>Interface \u00e0 \u00e9cran tactile : <\/strong> navigation intuitive avec les modes \u00ab Simply \u00bb (une touche) comprenant des programmes de d\u00e9marrage rapide pr\u00e9charg\u00e9s et \u00ab Individually \u00bb (personnalisable).<\/p>\n<\/div><\/div><\/div><\/div>\r\n\r\n<div class=\"et_pb_blurb_1 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_flex_module\"><div class=\"et_pb_blurb_content et_flex_module\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap et_pb_only_image_mode_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/arrow_green.png\" width=\"70\" height=\"70\" srcset=\"https:\/\/smartpulser.com\/wp-content\/uploads\/arrow_green.png 70w\" sizes=\"(max-width: 70px) 100vw, 70px\" class=\"wp-image-223236\" title=\"arrow_green\" \/><\/span><\/div><div class=\"et_pb_blurb_container\"><div class=\"et_pb_blurb_description\"><p><strong>Alimentation hybride : <\/strong> Passez sans difficult\u00e9 de la prise murale \u00e0 la batterie haute capacit\u00e9.<\/p>\n<\/div><\/div><\/div><\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n\r\n<div class=\"et_pb_row_17 et_pb_row et_grid_row et_animated cards-grid\">\r\n<div class=\"et_pb_column_21 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et-interaction-target-ugezgubc68 stats-grid\" data-interaction-trigger=\"5keq98ymoj\" data-interaction-target=\"ugezgubc68\">\r\n<div class=\"et_pb_row_18 et_pb_row et_pb_row_nested et_flex_row card-wrap\">\r\n<div class=\"et_pb_column_22 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_tabletWide card\">\r\n<div class=\"et_pb_row_19 et_pb_row et_pb_row_nested et_flex_row\">\r\n<div class=\"et_pb_column_23 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_12_24 et_flex_column_12_24_tablet et_flex_column_24_24_phone et_flex_column_12_24_tabletWide\">\r\n<div class=\"et_pb_image_12 et_pb_image et_pb_module et_flex_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/smartpulser_smat.png\" title=\"smartpulser_smat\" width=\"900\" height=\"600\" srcset=\"https:\/\/smartpulser.com\/wp-content\/uploads\/smartpulser_smat.png 900w, https:\/\/smartpulser.com\/wp-content\/uploads\/smartpulser_smat-480x320.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 900px, 100vw\" class=\"wp-image-210\" \/><\/span><\/div>\r\n<\/div>\r\n\r\n<div class=\"et_pb_column_24 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_12_24 et_flex_column_12_24_tablet et_flex_column_24_24_phone et_flex_column_12_24_tabletWide\">\r\n<div class=\"et_pb_group_30 et_pb_group et-last-child et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\">\r\n<div class=\"et_pb_image_13 et_pb_image et_pb_module et_flex_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/smat_white.png\" title=\"smat_white\" width=\"1433\" height=\"300\" srcset=\"https:\/\/smartpulser.com\/wp-content\/uploads\/smat_white.png 1433w, https:\/\/smartpulser.com\/wp-content\/uploads\/smat_white-1280x268.png 1280w, https:\/\/smartpulser.com\/wp-content\/uploads\/smat_white-980x205.png 980w, https:\/\/smartpulser.com\/wp-content\/uploads\/smat_white-480x100.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1433px, 100vw\" class=\"wp-image-222358\" \/><\/span><\/div>\r\n\r\n<div class=\"et_pb_heading_16 et_pb_heading et_pb_module et_flex_module\"><div class=\"et_pb_heading_container\"><h3 class=\"et_pb_module_header\">Applicateur pour tout le corps<\/h3><\/div><\/div>\r\n\r\n<div class=\"et_pb_blurb_2 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_flex_module\"><div class=\"et_pb_blurb_content et_flex_module\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap et_pb_only_image_mode_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/arrow_green.png\" width=\"70\" height=\"70\" srcset=\"https:\/\/smartpulser.com\/wp-content\/uploads\/arrow_green.png 70w\" sizes=\"(max-width: 70px) 100vw, 70px\" class=\"wp-image-223236\" title=\"arrow_green\" \/><\/span><\/div><div class=\"et_pb_blurb_container\"><div class=\"et_pb_blurb_description\"><p>Conception pliable en 4 segments comprenant 8 bobines \u00e0 fibres inductives (4 paires).<\/p>\n<\/div><\/div><\/div><\/div>\r\n\r\n<div class=\"et_pb_blurb_3 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_flex_module\"><div class=\"et_pb_blurb_content et_flex_module\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap et_pb_only_image_mode_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/arrow_green.png\" width=\"70\" height=\"70\" srcset=\"https:\/\/smartpulser.com\/wp-content\/uploads\/arrow_green.png 70w\" sizes=\"(max-width: 70px) 100vw, 70px\" class=\"wp-image-223236\" title=\"arrow_green\" \/><\/span><\/div><div class=\"et_pb_blurb_container\"><div class=\"et_pb_blurb_description\"><p>Forme d'onde en dents de scie triple.<\/p>\n<\/div><\/div><\/div><\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n\r\n<div class=\"et_pb_row_20 et_pb_row et_grid_row et_animated cards-grid\">\r\n<div class=\"et_pb_column_25 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et-interaction-target-j52zrp236o stats-grid\" data-interaction-trigger=\"kdxvvl4rf5\" data-interaction-target=\"j52zrp236o\">\r\n<div class=\"et_pb_row_21 et_pb_row et_pb_row_nested et_flex_row card-wrap\">\r\n<div class=\"et_pb_column_26 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_tabletWide card\">\r\n<div class=\"et_pb_row_22 et_pb_row et_pb_row_nested et_flex_row\">\r\n<div class=\"et_pb_column_27 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_12_24 et_flex_column_12_24_tablet et_flex_column_24_24_phone et_flex_column_12_24_tabletWide\">\r\n<div class=\"et_pb_image_14 et_pb_image et_pb_module et_flex_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/smartpulser_sbed.png\" title=\"smartpulser_sbed\" width=\"900\" height=\"600\" srcset=\"https:\/\/smartpulser.com\/wp-content\/uploads\/smartpulser_sbed.png 900w, https:\/\/smartpulser.com\/wp-content\/uploads\/smartpulser_sbed-480x320.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 900px, 100vw\" class=\"wp-image-213\" \/><\/span><\/div>\r\n<\/div>\r\n\r\n<div class=\"et_pb_column_28 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_12_24 et_flex_column_12_24_tablet et_flex_column_24_24_phone et_flex_column_12_24_tabletWide\">\r\n<div class=\"et_pb_group_31 et_pb_group et-last-child et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\">\r\n<div class=\"et_pb_image_15 et_pb_image et_pb_module et_flex_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/sbed_white.png\" title=\"sbed_white\" width=\"1378\" height=\"300\" srcset=\"https:\/\/smartpulser.com\/wp-content\/uploads\/sbed_white.png 1378w, https:\/\/smartpulser.com\/wp-content\/uploads\/sbed_white-1280x279.png 1280w, https:\/\/smartpulser.com\/wp-content\/uploads\/sbed_white-980x213.png 980w, https:\/\/smartpulser.com\/wp-content\/uploads\/sbed_white-480x104.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1378px, 100vw\" class=\"wp-image-222362\" \/><\/span><\/div>\r\n\r\n<div class=\"et_pb_heading_17 et_pb_heading et_pb_module et_flex_module\"><div class=\"et_pb_heading_container\"><h3 class=\"et_pb_module_header\">Applicateur pour tout le corps<\/h3><\/div><\/div>\r\n\r\n<div class=\"et_pb_blurb_4 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_flex_module\"><div class=\"et_pb_blurb_content et_flex_module\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap et_pb_only_image_mode_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/arrow_green.png\" width=\"70\" height=\"70\" srcset=\"https:\/\/smartpulser.com\/wp-content\/uploads\/arrow_green.png 70w\" sizes=\"(max-width: 70px) 100vw, 70px\" class=\"wp-image-223236\" title=\"arrow_green\" \/><\/span><\/div><div class=\"et_pb_blurb_container\"><div class=\"et_pb_blurb_description\"><p>Conception pliable en 4 segments comprenant 8 bobines \u00e0 fibres inductives (4 paires).<\/p>\n<\/div><\/div><\/div><\/div>\r\n\r\n<div class=\"et_pb_blurb_5 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_flex_module\"><div class=\"et_pb_blurb_content et_flex_module\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap et_pb_only_image_mode_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/arrow_green.png\" width=\"70\" height=\"70\" srcset=\"https:\/\/smartpulser.com\/wp-content\/uploads\/arrow_green.png 70w\" sizes=\"(max-width: 70px) 100vw, 70px\" class=\"wp-image-223236\" title=\"arrow_green\" \/><\/span><\/div><div class=\"et_pb_blurb_container\"><div class=\"et_pb_blurb_description\"><p><strong>Fonction \u00ab Dual-Control \u00bb : <\/strong> alimentez simultan\u00e9ment deux applicateurs S.Bed \u2013 id\u00e9al pour les couples..<\/p>\n<\/div><\/div><\/div><\/div>\r\n\r\n<div class=\"et_pb_blurb_6 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_flex_module\"><div class=\"et_pb_blurb_content et_flex_module\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap et_pb_only_image_mode_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/arrow_green.png\" width=\"70\" height=\"70\" srcset=\"https:\/\/smartpulser.com\/wp-content\/uploads\/arrow_green.png 70w\" sizes=\"(max-width: 70px) 100vw, 70px\" class=\"wp-image-223236\" title=\"arrow_green\" \/><\/span><\/div><div class=\"et_pb_blurb_container\"><div class=\"et_pb_blurb_description\"><p>Forme d'onde en dents de scie triple.<\/p>\n<\/div><\/div><\/div><\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n\r\n<div class=\"et_pb_row_23 et_pb_row et_grid_row et_animated cards-grid\">\r\n<div class=\"et_pb_column_29 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et-interaction-target-jthkirelva stats-grid\" data-interaction-trigger=\"s159v6smsp\" data-interaction-target=\"jthkirelva\">\r\n<div class=\"et_pb_row_24 et_pb_row et_pb_row_nested et_flex_row card-wrap\">\r\n<div class=\"et_pb_column_30 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_tabletWide card\">\r\n<div class=\"et_pb_row_25 et_pb_row et_pb_row_nested et_flex_row\">\r\n<div class=\"et_pb_column_31 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_12_24 et_flex_column_12_24_tablet et_flex_column_24_24_phone et_flex_column_12_24_tabletWide\">\r\n<div class=\"et_pb_image_16 et_pb_image et_pb_module et_flex_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/smartpulser_swrap.png\" title=\"smartpulser_swrap\" width=\"900\" height=\"600\" srcset=\"https:\/\/smartpulser.com\/wp-content\/uploads\/smartpulser_swrap.png 900w, https:\/\/smartpulser.com\/wp-content\/uploads\/smartpulser_swrap-480x320.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 900px, 100vw\" class=\"wp-image-214\" \/><\/span><\/div>\r\n<\/div>\r\n\r\n<div class=\"et_pb_column_32 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_12_24 et_flex_column_12_24_tablet et_flex_column_24_24_phone et_flex_column_12_24_tabletWide\">\r\n<div class=\"et_pb_group_32 et_pb_group et-last-child et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\">\r\n<div class=\"et_pb_image_17 et_pb_image et_pb_module et_flex_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/swrap_white.png\" title=\"swrap_white\" width=\"1722\" height=\"300\" srcset=\"https:\/\/smartpulser.com\/wp-content\/uploads\/swrap_white.png 1722w, https:\/\/smartpulser.com\/wp-content\/uploads\/swrap_white-1280x223.png 1280w, https:\/\/smartpulser.com\/wp-content\/uploads\/swrap_white-980x171.png 980w, https:\/\/smartpulser.com\/wp-content\/uploads\/swrap_white-480x84.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1722px, 100vw\" class=\"wp-image-222361\" \/><\/span><\/div>\r\n\r\n<div class=\"et_pb_heading_18 et_pb_heading et_pb_module et_flex_module\"><div class=\"et_pb_heading_container\"><h3 class=\"et_pb_module_header\">Applicateur local enveloppant<\/h3><\/div><\/div>\r\n\r\n<div class=\"et_pb_blurb_7 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_flex_module\"><div class=\"et_pb_blurb_content et_flex_module\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap et_pb_only_image_mode_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/arrow_green.png\" width=\"70\" height=\"70\" srcset=\"https:\/\/smartpulser.com\/wp-content\/uploads\/arrow_green.png 70w\" sizes=\"(max-width: 70px) 100vw, 70px\" class=\"wp-image-223236\" title=\"arrow_green\" \/><\/span><\/div><div class=\"et_pb_blurb_container\"><div class=\"et_pb_blurb_description\"><p>Conception enveloppante comprenant 2 bobines \u00e0 fibre inductive (1 paire)<\/p>\n<\/div><\/div><\/div><\/div>\r\n\r\n<div class=\"et_pb_blurb_8 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_flex_module\"><div class=\"et_pb_blurb_content et_flex_module\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap et_pb_only_image_mode_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/arrow_green.png\" width=\"70\" height=\"70\" srcset=\"https:\/\/smartpulser.com\/wp-content\/uploads\/arrow_green.png 70w\" sizes=\"(max-width: 70px) 100vw, 70px\" class=\"wp-image-223236\" title=\"arrow_green\" \/><\/span><\/div><div class=\"et_pb_blurb_container\"><div class=\"et_pb_blurb_description\"><p>Forme d'onde carr\u00e9e.<\/p>\n<\/div><\/div><\/div><\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n\r\n<div class=\"et_pb_row_26 et_pb_row et_grid_row et_animated cards-grid\">\r\n<div class=\"et_pb_column_33 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et-interaction-target-wqqohdrur1 stats-grid\" data-interaction-trigger=\"fhhfkf9ihd\" data-interaction-target=\"wqqohdrur1\">\r\n<div class=\"et_pb_row_27 et_pb_row et_pb_row_nested et_flex_row card-wrap\">\r\n<div class=\"et_pb_column_34 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_tabletWide card\">\r\n<div class=\"et_pb_row_28 et_pb_row et_pb_row_nested et_flex_row\">\r\n<div class=\"et_pb_column_35 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_12_24 et_flex_column_12_24_tablet et_flex_column_24_24_phone et_flex_column_12_24_tabletWide\">\r\n<div class=\"et_pb_image_18 et_pb_image et_pb_module et_flex_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/smartpulser_sbrain_coming_soon.png\" title=\"smartpulser_sbrain_coming_soon\" width=\"900\" height=\"600\" srcset=\"https:\/\/smartpulser.com\/wp-content\/uploads\/smartpulser_sbrain_coming_soon.png 900w, https:\/\/smartpulser.com\/wp-content\/uploads\/smartpulser_sbrain_coming_soon-480x320.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 900px, 100vw\" class=\"wp-image-215\" \/><\/span><\/div>\r\n<\/div>\r\n\r\n<div class=\"et_pb_column_36 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_12_24 et_flex_column_12_24_tablet et_flex_column_24_24_phone et_flex_column_12_24_tabletWide\">\r\n<div class=\"et_pb_group_33 et_pb_group et-last-child et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\">\r\n<div class=\"et_pb_image_19 et_pb_image et_pb_module et_flex_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/sbrain_white.png\" title=\"sbrain_white\" width=\"1767\" height=\"300\" srcset=\"https:\/\/smartpulser.com\/wp-content\/uploads\/sbrain_white.png 1767w, https:\/\/smartpulser.com\/wp-content\/uploads\/sbrain_white-1280x217.png 1280w, https:\/\/smartpulser.com\/wp-content\/uploads\/sbrain_white-980x166.png 980w, https:\/\/smartpulser.com\/wp-content\/uploads\/sbrain_white-480x81.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1767px, 100vw\" class=\"wp-image-222360\" \/><\/span><\/div>\r\n\r\n<div class=\"et_pb_heading_19 et_pb_heading et_pb_module et_flex_module\"><div class=\"et_pb_heading_container\"><h3 class=\"et_pb_module_header\">Lunettes AVE<\/h3><\/div><\/div>\r\n\r\n<div class=\"et_pb_blurb_9 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_flex_module\"><div class=\"et_pb_blurb_content et_flex_module\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap et_pb_only_image_mode_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/arrow_green.png\" width=\"70\" height=\"70\" srcset=\"https:\/\/smartpulser.com\/wp-content\/uploads\/arrow_green.png 70w\" sizes=\"(max-width: 70px) 100vw, 70px\" class=\"wp-image-223236\" title=\"arrow_green\" \/><\/span><\/div><div class=\"et_pb_blurb_container\"><div class=\"et_pb_blurb_description\"><p>Synchronisation audiovisuelle. Synchronisation des fr\u00e9quences de scintillement, des couleurs et des tonalit\u00e9s avec l'impulsion magn\u00e9tique pour une exp\u00e9rience multisensorielle.<\/p>\n<\/div><\/div><\/div><\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n\r\n<div class=\"et_pb_row_29 et_pb_row et_grid_row et_animated cards-grid\">\r\n<div class=\"et_pb_column_37 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et-interaction-target-u9g0ci1d2h stats-grid\" data-interaction-trigger=\"dyi7jagk6q\" data-interaction-target=\"u9g0ci1d2h\">\r\n<div class=\"et_pb_row_30 et_pb_row et_pb_row_nested et_flex_row card-wrap\">\r\n<div class=\"et_pb_column_38 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_tabletWide card\">\r\n<div class=\"et_pb_row_31 et_pb_row et_pb_row_nested et_flex_row\">\r\n<div class=\"et_pb_column_39 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_12_24 et_flex_column_12_24_tablet et_flex_column_24_24_phone et_flex_column_12_24_tabletWide\">\r\n<div class=\"et_pb_image_20 et_pb_image et_pb_module et_flex_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/smartpulser_sface_coming_soon.png\" title=\"smartpulser_sface_coming_soon\" width=\"900\" height=\"600\" srcset=\"https:\/\/smartpulser.com\/wp-content\/uploads\/smartpulser_sface_coming_soon.png 900w, https:\/\/smartpulser.com\/wp-content\/uploads\/smartpulser_sface_coming_soon-480x320.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 900px, 100vw\" class=\"wp-image-216\" \/><\/span><\/div>\r\n<\/div>\r\n\r\n<div class=\"et_pb_column_40 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_12_24 et_flex_column_12_24_tablet et_flex_column_24_24_phone et_flex_column_12_24_tabletWide\">\r\n<div class=\"et_pb_group_34 et_pb_group et-last-child et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\">\r\n<div class=\"et_pb_image_21 et_pb_image et_pb_module et_flex_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/sface_white.png\" title=\"sface_white\" width=\"1689\" height=\"300\" srcset=\"https:\/\/smartpulser.com\/wp-content\/uploads\/sface_white.png 1689w, https:\/\/smartpulser.com\/wp-content\/uploads\/sface_white-1280x227.png 1280w, https:\/\/smartpulser.com\/wp-content\/uploads\/sface_white-980x174.png 980w, https:\/\/smartpulser.com\/wp-content\/uploads\/sface_white-480x85.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1689px, 100vw\" class=\"wp-image-222359\" \/><\/span><\/div>\r\n\r\n<div class=\"et_pb_heading_20 et_pb_heading et_pb_module et_flex_module\"><div class=\"et_pb_heading_container\"><h3 class=\"et_pb_module_header\">Masque de beaut\u00e9<\/h3><\/div><\/div>\r\n\r\n<div class=\"et_pb_blurb_10 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_flex_module\"><div class=\"et_pb_blurb_content et_flex_module\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap et_pb_only_image_mode_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/arrow_green.png\" width=\"70\" height=\"70\" srcset=\"https:\/\/smartpulser.com\/wp-content\/uploads\/arrow_green.png 70w\" sizes=\"(max-width: 70px) 100vw, 70px\" class=\"wp-image-223236\" title=\"arrow_green\" \/><\/span><\/div><div class=\"et_pb_blurb_container\"><div class=\"et_pb_blurb_description\"><p>Un appareil de pointe qui int\u00e8gre des bobines de fibres inductives, des couleurs et de la lumi\u00e8re pour cr\u00e9er une exp\u00e9rience compl\u00e8te de beaut\u00e9 et de bien-\u00eatre pour la t\u00eate, le cou et le visage.<\/p>\n<\/div><\/div><\/div><\/div>\r\n\r\n<div class=\"et_pb_blurb_11 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_flex_module\"><div class=\"et_pb_blurb_content et_flex_module\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap et_pb_only_image_mode_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/arrow_green.png\" width=\"70\" height=\"70\" srcset=\"https:\/\/smartpulser.com\/wp-content\/uploads\/arrow_green.png 70w\" sizes=\"(max-width: 70px) 100vw, 70px\" class=\"wp-image-223236\" title=\"arrow_green\" \/><\/span><\/div><div class=\"et_pb_blurb_container\"><div class=\"et_pb_blurb_description\"><p>Forme d'onde carr\u00e9e.<\/p>\n<\/div><\/div><\/div><\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/section>\r\n\r\n<section class=\"et_pb_section_4 et_pb_section et_section_regular et_flex_section\" id=\"vitalit&amp;lt;\">\r\n<div class=\"et_pb_row_32 et_pb_row et_flex_row\">\r\n<div class=\"et_pb_column_41 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_tabletWide\">\r\n<div class=\"et_pb_group_35 et_pb_group et-last-child et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough stacked-header\">\r\n<div class=\"et_pb_heading_21 et_pb_heading et_pb_module et_flex_module\"><div class=\"et_pb_heading_container\"><h2 class=\"et_pb_module_header\">Optimisez votre vie, une impulsion \u00e0 la fois.<\/h2><\/div><\/div>\r\n\r\n<div class=\"et_pb_heading_22 et_pb_heading et_pb_module et_flex_module headline-gradient\"><div class=\"et_pb_heading_container\"><h2 class=\"et_pb_module_header\">Vitalit\u00e9, \u00e9quilibre et bien-\u00eatre holistique<\/h2><\/div><\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n\r\n<div class=\"et_pb_row_33 et_pb_row et_grid_row cards-grid\">\r\n<div class=\"et_pb_column_42 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_animated et-interaction-target-o9bqaruln0 stats-grid\" data-interaction-trigger=\"kt9uli5ozi\" data-interaction-target=\"o9bqaruln0\">\r\n<div class=\"et_pb_row_34 et_pb_row et_pb_row_nested et_flex_row card-wrap\">\r\n<div class=\"et_pb_column_43 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_tabletWide card\">\r\n<div class=\"et_pb_group_36 et_pb_group et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\" id=\"overlay_unique_id_222969\">\r\n<div class=\"et_pb_image_22 et_pb_image et_pb_module et_flex_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/card_from_clinical_treatment_to_holistic_living_2.jpg\" title=\"card_from_clinical_treatment_to_holistic_living_2\" width=\"800\" height=\"450\" srcset=\"https:\/\/smartpulser.com\/wp-content\/uploads\/card_from_clinical_treatment_to_holistic_living_2.jpg 800w\" sizes=\"(max-width: 800px) 100vw, 800px\" class=\"wp-image-222377\" \/><\/span><\/div>\r\n\r\n<div class=\"et_pb_heading_23 et_pb_heading et_pb_module et_flex_module\"><div class=\"et_pb_heading_container\"><h5 class=\"et_pb_module_header\">Du traitement clinique \u00e0 un mode de vie holistique<\/h5><\/div><\/div>\r\n\r\n<div class=\"et_pb_text_17 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p>La PEMF \u00e9volue d'un traitement strictement clinique vers une solution de bien-\u00eatre quotidienne et s\u00fbre, con\u00e7ue pour l'\u00e9quilibre et la pr\u00e9vention. Gr\u00e2ce \u00e0 la technologie \u00e0 tr\u00e8s basse fr\u00e9quence, SmartPulser red\u00e9finit la mani\u00e8re dont nous prenons soin de notre sant\u00e9 \u00e0 long terme : en douceur, en toute s\u00e9curit\u00e9 et de mani\u00e8re proactive.<\/p>\n<\/div><\/div>\r\n<\/div>\r\n\r\n<div class=\"et_pb_group_37 et_pb_group et-last-child et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\" id=\"overlay_unique_id_222969\">\r\n<div class=\"et_pb_group_38 et_pb_group et-last-child et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\">\r\n<div class=\"et_pb_text_18 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p>En savoir plus<\/p>\n<\/div><\/div>\r\n\r\n<div class=\"et_pb_image_23 et_pb_image et_pb_module et_flex_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/plus-icon-green-white.svg\" title=\"plus-icon-green-white\" class=\"wp-image-220967\" \/><\/span><\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n\r\n<div class=\"et_pb_column_44 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_animated et-interaction-target-k8oyipbvv4 stats-grid\" data-interaction-trigger=\"zlpa79odhf\" data-interaction-target=\"k8oyipbvv4\">\r\n<div class=\"et_pb_row_35 et_pb_row et_pb_row_nested et_flex_row card-wrap\">\r\n<div class=\"et_pb_column_45 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_tabletWide card\">\r\n<div class=\"et_pb_group_39 et_pb_group et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\" id=\"overlay_unique_id_222971\">\r\n<div class=\"et_pb_image_24 et_pb_image et_pb_module et_flex_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/card_the_shift_to_regulation_technology_2.jpg\" title=\"card_the_shift_to_regulation_technology_2\" width=\"800\" height=\"450\" srcset=\"https:\/\/smartpulser.com\/wp-content\/uploads\/card_the_shift_to_regulation_technology_2.jpg 800w\" sizes=\"(max-width: 800px) 100vw, 800px\" class=\"wp-image-222378\" \/><\/span><\/div>\r\n\r\n<div class=\"et_pb_heading_24 et_pb_heading et_pb_module et_flex_module\"><div class=\"et_pb_heading_container\"><h5 class=\"et_pb_module_header\">Le passage \u00e0 la \u00ab technologie de r\u00e9gulation \u00bb<\/h5><\/div><\/div>\r\n\r\n<div class=\"et_pb_text_19 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p>Dans un monde marqu\u00e9 par le stress et un \u00ab bruit \u00bb constant, SmartPulser inaugure une nouvelle \u00e8re de r\u00e9gulation douce, rempla\u00e7ant les interventions agressives. En agissant en harmonie avec les rythmes naturels de votre corps, il favorise l'\u00e9quilibre, la r\u00e9silience et la vitalit\u00e9 au quotidien.<\/p>\n<\/div><\/div>\r\n<\/div>\r\n\r\n<div class=\"et_pb_group_40 et_pb_group et-last-child et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\" id=\"overlay_unique_id_222971\">\r\n<div class=\"et_pb_group_41 et_pb_group et-last-child et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\">\r\n<div class=\"et_pb_text_20 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p>En savoir plus<\/p>\n<\/div><\/div>\r\n\r\n<div class=\"et_pb_image_25 et_pb_image et_pb_module et_flex_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/plus-icon-green-white.svg\" title=\"plus-icon-green-white\" class=\"wp-image-220967\" \/><\/span><\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n\r\n<div class=\"et_pb_column_46 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_animated et-interaction-target-jo4ils138c stats-grid\" data-interaction-trigger=\"pk2l4qazh8\" data-interaction-target=\"jo4ils138c\">\r\n<div class=\"et_pb_row_36 et_pb_row et_pb_row_nested et_flex_row card-wrap\">\r\n<div class=\"et_pb_column_47 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_tabletWide card\">\r\n<div class=\"et_pb_group_42 et_pb_group et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\" id=\"overlay_unique_id_222973\">\r\n<div class=\"et_pb_image_26 et_pb_image et_pb_module et_flex_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/card_profound_benefits_zero_risk_2.jpg\" title=\"card_profound_benefits_zero_risk_2\" width=\"800\" height=\"450\" srcset=\"https:\/\/smartpulser.com\/wp-content\/uploads\/card_profound_benefits_zero_risk_2.jpg 800w\" sizes=\"(max-width: 800px) 100vw, 800px\" class=\"wp-image-222379\" \/><\/span><\/div>\r\n\r\n<div class=\"et_pb_heading_25 et_pb_heading et_pb_module et_flex_module\"><div class=\"et_pb_heading_container\"><h5 class=\"et_pb_module_header\">Des bienfaits profonds, z\u00e9ro risque<\/h5><\/div><\/div>\r\n\r\n<div class=\"et_pb_text_21 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p>SmartPulser prouve qu'un bien-\u00eatre optimal ne n\u00e9cessite pas d'\u00eatre invasif : il offre des bienfaits profonds gr\u00e2ce \u00e0 une approche douce et sans risque. Con\u00e7u pour s'adapter \u00e0 tous les modes de vie, il soutient votre corps naturellement, favorisant la r\u00e9cup\u00e9ration, l'\u00e9quilibre et le bien-\u00eatre g\u00e9n\u00e9ral.<\/p>\n<\/div><\/div>\r\n<\/div>\r\n\r\n<div class=\"et_pb_group_43 et_pb_group et-last-child et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\" id=\"overlay_unique_id_222973\">\r\n<div class=\"et_pb_group_44 et_pb_group et-last-child et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\">\r\n<div class=\"et_pb_text_22 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p>En savoir plus<\/p>\n<\/div><\/div>\r\n\r\n<div class=\"et_pb_image_27 et_pb_image et_pb_module et_flex_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/plus-icon-green-white.svg\" title=\"plus-icon-green-white\" class=\"wp-image-220967\" \/><\/span><\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n\r\n<div class=\"et_pb_column_48 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_animated et-interaction-target-4705nt1np8 stats-grid\" data-interaction-trigger=\"3v3zhmogv7\" data-interaction-target=\"4705nt1np8\">\r\n<div class=\"et_pb_row_37 et_pb_row et_pb_row_nested et_flex_row card-wrap\">\r\n<div class=\"et_pb_column_49 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_tabletWide card\">\r\n<div class=\"et_pb_group_45 et_pb_group et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\" id=\"overlay_unique_id_222975\">\r\n<div class=\"et_pb_image_28 et_pb_image et_pb_module et_flex_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/card_an_active_lifestyle_partner.jpg\" title=\"card_an_active_lifestyle_partner\" width=\"800\" height=\"450\" srcset=\"https:\/\/smartpulser.com\/wp-content\/uploads\/card_an_active_lifestyle_partner.jpg 800w\" sizes=\"(max-width: 800px) 100vw, 800px\" class=\"wp-image-222372\" \/><\/span><\/div>\r\n\r\n<div class=\"et_pb_heading_26 et_pb_heading et_pb_module et_flex_module\"><div class=\"et_pb_heading_container\"><h5 class=\"et_pb_module_header\">Un partenaire pour un mode de vie actif<\/h5><\/div><\/div>\r\n\r\n<div class=\"et_pb_text_23 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p>SmartPulser n'est plus un appareil que l'on range : c'est un compagnon discret qui vous accompagne \u00e0 chaque instant de la journ\u00e9e. De l'\u00e9nergie et la concentration \u00e0 la relaxation et au sommeil profond, il s'adapte \u00e0 votre mode de vie, o\u00f9 que vous soyez.<\/p>\n<\/div><\/div>\r\n<\/div>\r\n\r\n<div class=\"et_pb_group_46 et_pb_group et-last-child et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\" id=\"overlay_unique_id_222975\">\r\n<div class=\"et_pb_group_47 et_pb_group et-last-child et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\">\r\n<div class=\"et_pb_text_24 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p>En savoir plus<\/p>\n<\/div><\/div>\r\n\r\n<div class=\"et_pb_image_29 et_pb_image et_pb_module et_flex_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/plus-icon-green-white.svg\" title=\"plus-icon-green-white\" class=\"wp-image-220967\" \/><\/span><\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n\r\n<div class=\"et_pb_column_50 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_animated et-interaction-target-wdc9bygp82 stats-grid\" data-interaction-trigger=\"s8zuin00ln\" data-interaction-target=\"wdc9bygp82\">\r\n<div class=\"et_pb_row_38 et_pb_row et_pb_row_nested et_flex_row card-wrap\">\r\n<div class=\"et_pb_column_51 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_tabletWide card\">\r\n<div class=\"et_pb_group_48 et_pb_group et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\" id=\"overlay_unique_id_222977\">\r\n<div class=\"et_pb_image_30 et_pb_image et_pb_module et_flex_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/card_a_new_era_of_holistic_health_in_harmony_with_nature.jpg\" title=\"card_a_new_era_of_holistic_health_in_harmony_with_nature\" width=\"800\" height=\"450\" srcset=\"https:\/\/smartpulser.com\/wp-content\/uploads\/card_a_new_era_of_holistic_health_in_harmony_with_nature.jpg 800w\" sizes=\"(max-width: 800px) 100vw, 800px\" class=\"wp-image-222374\" \/><\/span><\/div>\r\n\r\n<div class=\"et_pb_heading_27 et_pb_heading et_pb_module et_flex_module\"><div class=\"et_pb_heading_container\"><h5 class=\"et_pb_module_header\">Une nouvelle \u00e8re de sant\u00e9 naturelle et holistique<\/h5><\/div><\/div>\r\n\r\n<div class=\"et_pb_text_25 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p>Entrez dans une nouvelle \u00e8re de sant\u00e9 holistique avec SmartPulser, con\u00e7u pour s'aligner sur les rythmes naturels de votre corps. Il favorise un meilleur sommeil, une r\u00e9duction du stress, un regain d'\u00e9nergie et une plus grande clart\u00e9 mentale, de mani\u00e8re simple et efficace.<\/p>\n<\/div><\/div>\r\n<\/div>\r\n\r\n<div class=\"et_pb_group_49 et_pb_group et-last-child et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\" id=\"overlay_unique_id_222977\">\r\n<div class=\"et_pb_group_50 et_pb_group et-last-child et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\">\r\n<div class=\"et_pb_text_26 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p>En savoir plus<\/p>\n<\/div><\/div>\r\n\r\n<div class=\"et_pb_image_31 et_pb_image et_pb_module et_flex_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/plus-icon-green-white.svg\" title=\"plus-icon-green-white\" class=\"wp-image-220967\" \/><\/span><\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n\r\n<div class=\"et_pb_column_52 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_animated et-interaction-target-0afb8sangx stats-grid\" data-interaction-trigger=\"yr17ivr7tx\" data-interaction-target=\"0afb8sangx\">\r\n<div class=\"et_pb_row_39 et_pb_row et_pb_row_nested et_flex_row card-wrap\">\r\n<div class=\"et_pb_column_53 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_tabletWide card\">\r\n<div class=\"et_pb_group_51 et_pb_group et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\" id=\"overlay_unique_id_222979\">\r\n<div class=\"et_pb_image_32 et_pb_image et_pb_module et_flex_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/card_why_resonance_is_the_key_to_wellness.jpg\" title=\"card_why_resonance_is_the_key_to_wellness\" width=\"800\" height=\"450\" srcset=\"https:\/\/smartpulser.com\/wp-content\/uploads\/card_why_resonance_is_the_key_to_wellness.jpg 800w\" sizes=\"(max-width: 800px) 100vw, 800px\" class=\"wp-image-222376\" \/><\/span><\/div>\r\n\r\n<div class=\"et_pb_heading_28 et_pb_heading et_pb_module et_flex_module\"><div class=\"et_pb_heading_container\"><h5 class=\"et_pb_module_header\">Pourquoi la \u00ab r\u00e9sonance \u00bb est la cl\u00e9 du bien-\u00eatre<\/h5><\/div><\/div>\r\n\r\n<div class=\"et_pb_text_27 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p>SmartPulser red\u00e9finit le bien-\u00eatre en agissant sur les \u00ab fen\u00eatres biologiques \u00bb naturelles de votre corps plut\u00f4t qu\u2019en s\u2019appuyant sur la force ou l\u2019intensit\u00e9. Doux, personnalis\u00e9 et sans risque, il offre des bienfaits cumulatifs qui s\u2019int\u00e8grent parfaitement \u00e0 votre quotidien.<\/p>\n<\/div><\/div>\r\n<\/div>\r\n\r\n<div class=\"et_pb_group_52 et_pb_group et-last-child et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\" id=\"overlay_unique_id_222979\">\r\n<div class=\"et_pb_group_53 et_pb_group et-last-child et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\">\r\n<div class=\"et_pb_text_28 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p>En savoir plus<\/p>\n<\/div><\/div>\r\n\r\n<div class=\"et_pb_image_33 et_pb_image et_pb_module et_flex_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/plus-icon-green-white.svg\" title=\"plus-icon-green-white\" class=\"wp-image-220967\" \/><\/span><\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/section>\r\n\r\n<section class=\"et_pb_section_5 et_pb_section et_section_regular et_flex_section\" id=\"contact-card\">\r\n<div class=\"et_pb_row_40 et_pb_row et_block_row et-interaction-target-exbed7a56b contact-card\" data-interaction-target=\"exbed7a56b\">\r\n<div class=\"et_pb_column_54 et_pb_column et_pb_column_4_4 et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough\">\r\n<div class=\"et_pb_group_54 et_pb_group et-last-child et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\">\r\n<div class=\"et_pb_heading_29 et_pb_heading et_pb_module et_flex_module\"><div class=\"et_pb_heading_container\"><h2 class=\"et_pb_module_header\">La philosophie de SmartPulser<\/h2><\/div><\/div>\r\n\r\n<div class=\"et_pb_text_29 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p>Nous n'utilisons pas de force \u00e0 haute intensit\u00e9 pour \u00ab choquer \u00bb le corps. Nous utilisons la fid\u00e9lit\u00e9, la r\u00e9sonance et le timing pour \u00ab rappeler \u00bb au corps comment activer ses propres capacit\u00e9s d'auto-gu\u00e9rison \u2013 de mani\u00e8re extr\u00eamement s\u00fbre et avec la plus grande pr\u00e9cision !<\/p>\n<\/div><\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/section>\r\n\r\n<div class=\"et_pb_section_6 et_pb_section et_section_regular et_flex_section\">\r\n<div class=\"et_pb_row_41 et_pb_row et_flex_row\">\r\n<div class=\"et_pb_column_55 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_tabletWide\">\r\n<div class=\"et_pb_group_55 et_pb_group et-last-child et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\" id=\"overlay_unique_id_222981\">\r\n<div class=\"et_pb_group_56 et_pb_group et-last-child et_pb_module et_flex_group et_pb_css_mix_blend_mode_passthrough\">\r\n<div class=\"et_pb_text_30 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p>\u00c0 propos de nous<\/p>\n<\/div><\/div>\r\n\r\n<div class=\"et_pb_image_34 et_pb_image et_pb_module et_flex_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/smartpulser.com\/wp-content\/uploads\/plus-icon-green-white.svg\" title=\"plus-icon-green-white\" class=\"wp-image-220967\" \/><\/span><\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n\r\n<section class=\"et_pb_section_7 et_pb_section et_section_regular et_flex_section\" id=\"faq\">\r\n<div class=\"et_pb_row_42 et_pb_row et_flex_row\">\r\n<div class=\"et_pb_column_56 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_tabletWide\">\r\n<div class=\"et_pb_heading_30 et_pb_heading et_pb_module et_flex_module\"><div class=\"et_pb_heading_container\"><h2 class=\"et_pb_module_header\">Assistance<\/h2><\/div><\/div>\r\n\r\n<div class=\"et_pb_heading_31 et_pb_heading et_pb_module et_flex_module headline-gradient\"><div class=\"et_pb_heading_container\"><h2 class=\"et_pb_module_header\">Foire aux questions <\/h2><\/div><\/div>\r\n<\/div>\r\n<\/div>\r\n\r\n<div class=\"et_pb_row_43 et_pb_row et_flex_row et_animated\">\r\n<div class=\"et_pb_column_57 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_tabletWide\">\r\n<div class=\"et_pb_heading_32 et_pb_heading et_pb_module et_flex_module\"><div class=\"et_pb_heading_container\"><h2 class=\"et_pb_module_header\">Informations g\u00e9n\u00e9rales sur les CEMP<\/h2><\/div><\/div>\r\n\r\n<div class=\"et_pb_accordion_0 et_pb_accordion et_pb_module et_flex_module\">\r\n<div class=\"et_pb_accordion_item_0 et_pb_accordion_item et_pb_toggle et_pb_module et_pb_toggle_open et_flex_module\"><h5 class=\"et_pb_toggle_title\">Qu'est-ce que le CEMP \u00e0 faible intensit\u00e9 et comment fonctionne-t-il ? <\/h5><div class=\"et_pb_toggle_content et_flex_module\"><p>CEMP signifie \u00ab champ \u00e9lectromagn\u00e9tique puls\u00e9 \u00bb. Il s'agit d'une technologie qui \u00e9met des impulsions \u00e9lectromagn\u00e9tiques \u00e0 tr\u00e8s basse fr\u00e9quence con\u00e7ues pour imiter les champs \u00e9lectromagn\u00e9tiques naturels de la Terre et de l'ionosph\u00e8re. Ces impulsions interagissent en douceur avec l'\u00e9lectrobiologie naturelle de votre corps pour favoriser le bien-\u00eatre cellulaire, la relaxation et la r\u00e9cup\u00e9ration.<\/p>\n<\/div><\/div>\r\n\r\n<div class=\"et_pb_accordion_item_1 et_pb_accordion_item et_pb_toggle et_pb_module et_pb_toggle_close et_flex_module\"><h5 class=\"et_pb_toggle_title\">En quoi le SmartPulser se distingue-t-il des autres appareils CEMP ?<\/h5><div class=\"et_pb_toggle_content et_flex_module\"><p><strong>SmartPulser introduit trois technologies in\u00e9dites dans le secteur :<\/strong><\/p>\n<p><strong>Bobines \u00e0 fibres inductives : <\/strong><br \/>\nune alternative flexible et de haute pr\u00e9cision aux bobines de cuivre traditionnelles, pour une distribution du champ plus uniforme et plus propre, ainsi qu'une efficacit\u00e9 accrue.<\/p>\n<p><strong>Horloge organique int\u00e9gr\u00e9e :<br \/>\n<\/strong>un syst\u00e8me qui aligne automatiquement la fr\u00e9quence sur les rythmes circadiens naturels de votre corps.<\/p>\n<p><strong>Double commande S.Bed :<br \/>\n<\/strong>la possibilit\u00e9 de faire fonctionner deux applicateurs de sommeil simultan\u00e9ment \u00e0 partir d'une seule unit\u00e9 de commande.<\/p>\n<p><strong>Accessoires qui renforcent les bienfaits holistiques sur le bien-\u00eatre :<br \/>\n<\/strong> S.Brain = synchronisation audiovisuelle (AVE)<br \/>\nS.Face = CEMP, lumi\u00e8re et couleur pour la t\u00eate, le cou et le visage<\/p>\n<\/div><\/div>\r\n\r\n<div class=\"et_pb_accordion_item_2 et_pb_accordion_item et_pb_toggle et_pb_module et_pb_toggle_close et_flex_module\"><h5 class=\"et_pb_toggle_title\">Vais-je ressentir quelque chose pendant une s\u00e9ance ?<\/h5><div class=\"et_pb_toggle_content et_flex_module\"><p>Comme le SmartPulser utilise des niveaux d'intensit\u00e9 et de fr\u00e9quence extr\u00eamement faibles, la plupart des utilisateurs ne ressentent aucune sensation physique telle que des contractions ou de la chaleur. Au contraire, les utilisateurs rapportent g\u00e9n\u00e9ralement une sensation de relaxation profonde, un \u00ab apaisement \u00bb de l'esprit, ou une l\u00e9g\u00e8re sensation de chaleur ou de picotements \u00e0 mesure que le corps entre dans un \u00e9tat de repos et de r\u00e9cup\u00e9ration.<\/p>\n<\/div><\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/section>\r\n\r\n<div class=\"et_pb_section_8 et_pb_section et_section_regular et_flex_section\">\r\n<div class=\"et_pb_row_44 et_pb_row et_flex_row et_animated\">\r\n<div class=\"et_pb_column_58 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_tabletWide\">\r\n<div class=\"et_pb_heading_33 et_pb_heading et_pb_module et_flex_module\"><div class=\"et_pb_heading_container\"><h2 class=\"et_pb_module_header\">Utilisation du SmartPulser<\/h2><\/div><\/div>\r\n\r\n<div class=\"et_pb_accordion_1 et_pb_accordion et_pb_module et_flex_module\">\r\n<div class=\"et_pb_accordion_item_3 et_pb_accordion_item et_pb_toggle et_pb_module et_pb_toggle_open et_flex_module\"><h5 class=\"et_pb_toggle_title\">\u00c0 quelle fr\u00e9quence dois-je utiliser le SmartPulser ?<\/h5><div class=\"et_pb_toggle_content et_flex_module\"><p>Pour obtenir des r\u00e9sultats optimaux, la r\u00e9gularit\u00e9 est essentielle. Nous recommandons une utilisation quotidienne. Une s\u00e9ance matinale type sur le Whole Body S.Mat dure entre 8 et 24 minutes pour bien commencer la journ\u00e9e, tandis que le S.Bed peut \u00eatre utilis\u00e9 au moment du coucher pour favoriser un sommeil profond.<\/p>\n<\/div><\/div>\r\n\r\n<div class=\"et_pb_accordion_item_4 et_pb_accordion_item et_pb_toggle et_pb_module et_pb_toggle_close et_flex_module\"><h5 class=\"et_pb_toggle_title\">Quelle est la diff\u00e9rence entre les modes \u00ab Simply \u00bb et \u00ab Individually \u00bb ?<\/h5><div class=\"et_pb_toggle_content et_flex_module\"><p><strong>Mode \u00ab Simply \u00bb : <\/strong> <br \/>Con\u00e7u pour une utilisation simple. L'appareil ex\u00e9cute des programmes de d\u00e9marrage rapide pr\u00e9install\u00e9s et utilise l'horloge biologique pour s\u00e9lectionner automatiquement la combinaison de signaux id\u00e9ale en fonction de l'heure de la journ\u00e9e. Il suffit d'appuyer sur \u00ab Start \u00bb.<\/p>\n<p><strong>Mode \u00ab Individually \u00bb : <br \/><\/strong>destin\u00e9 aux utilisateurs avanc\u00e9s qui souhaitent s\u00e9lectionner des mod\u00e8les d\u2019horloge organique, des intensit\u00e9s et des dur\u00e9es sp\u00e9cifiques pour atteindre des objectifs de bien-\u00eatre cibl\u00e9s. C\u2019est \u00e0 vous de choisir.<\/p>\n<\/div><\/div>\r\n\r\n<div class=\"et_pb_accordion_item_5 et_pb_accordion_item et_pb_toggle et_pb_module et_pb_toggle_close et_flex_module\"><h5 class=\"et_pb_toggle_title\">Puis-je utiliser l'appareil pendant qu'il est en charge ?<\/h5><div class=\"et_pb_toggle_content et_flex_module\"><p>Oui. Le SmartPulser se distingue par sa conception \u00e0 alimentation hybride. Vous pouvez l'utiliser branch\u00e9 sur une prise murale pour une utilisation fixe (au lit, dans le salon ou au bureau) ou le faire fonctionner gr\u00e2ce \u00e0 sa batterie interne haute capacit\u00e9 pour une portabilit\u00e9 totale o\u00f9 que vous alliez (batterie externe en option).<\/p>\n<\/div><\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n\r\n<div class=\"et_pb_section_9 et_pb_section et_section_regular et_flex_section\">\r\n<div class=\"et_pb_row_45 et_pb_row et_flex_row et_animated\">\r\n<div class=\"et_pb_column_59 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_tabletWide\">\r\n<div class=\"et_pb_heading_34 et_pb_heading et_pb_module et_flex_module\"><div class=\"et_pb_heading_container\"><h2 class=\"et_pb_module_header\">Applicateurs et accessoires<\/h2><\/div><\/div>\r\n\r\n<div class=\"et_pb_accordion_2 et_pb_accordion et_pb_module et_flex_module\">\r\n<div class=\"et_pb_accordion_item_6 et_pb_accordion_item et_pb_toggle et_pb_module et_pb_toggle_open et_flex_module\"><h5 class=\"et_pb_toggle_title\">Deux personnes peuvent-elles utiliser le S.Bed en m\u00eame temps ?<\/h5><div class=\"et_pb_toggle_content et_flex_module\"><p>Oui. L'unit\u00e9 de commande SmartPulser est con\u00e7ue pour un fonctionnement double, ce qui lui permet d'alimenter et de contr\u00f4ler simultan\u00e9ment deux applicateurs S.Bed. Cela en fait la solution id\u00e9ale pour les couples qui souhaitent optimiser ensemble leur environnement de sommeil.<\/p>\n<\/div><\/div>\r\n\r\n<div class=\"et_pb_accordion_item_7 et_pb_accordion_item et_pb_toggle et_pb_module et_pb_toggle_close et_flex_module\"><h5 class=\"et_pb_toggle_title\">Comment les lunettes AVE fonctionnent-elles avec le CEMP ?<\/h5><div class=\"et_pb_toggle_content et_flex_module\"><p>Nos lunettes d'entra\u00eenement audiovisuel (AVE) synchronisent les impulsions lumineuses et sonores avec la fr\u00e9quence magn\u00e9tique de l'unit\u00e9 de commande. Cette approche \u00ab multisensorielle \u00bb aide le cerveau \u00e0 atteindre plus rapidement l'\u00e9tat souhait\u00e9, qu'il s'agisse d'une relaxation profonde (Delta\/Th\u00eata) ou d'une concentration maximale (Alpha\/B\u00eata).<\/p>\n<\/div><\/div>\r\n\r\n<div class=\"et_pb_accordion_item_8 et_pb_accordion_item et_pb_toggle et_pb_module et_pb_toggle_close et_flex_module\"><h5 class=\"et_pb_toggle_title\">L'applicateur Local S.Wrap est-il r\u00e9serv\u00e9 aux athl\u00e8tes ? <\/h5><div class=\"et_pb_toggle_content et_flex_module\"><p>Pas du tout. Si les athl\u00e8tes appr\u00e9cient le Square Wave pour la r\u00e9cup\u00e9ration musculaire, le Local S.Wrap est id\u00e9al pour toute personne souhaitant apporter un soutien cibl\u00e9 \u00e0 des zones sp\u00e9cifiques telles que le bas du dos, les genoux ou les \u00e9paules apr\u00e8s une longue journ\u00e9e de travail ou de voyage.<\/p>\n<\/div><\/div>\r\n\r\n<div class=\"et_pb_accordion_item_9 et_pb_accordion_item et_pb_toggle et_pb_module et_pb_toggle_close et_flex_module\"><h5 class=\"et_pb_toggle_title\">Est-il possible de mettre \u00e0 jour le SmartPulser ?<\/h5><div class=\"et_pb_toggle_content et_flex_module\"><p>Le SmartPulser est l'un des rares syst\u00e8mes disponibles pouvant \u00eatre mis \u00e0 jour \u00e0 mesure que de nouvelles fonctionnalit\u00e9s sont lanc\u00e9es ou que d'\u00e9ventuels bugs sont corrig\u00e9s. Ce service est fourni gratuitement et peut \u00eatre effectu\u00e9 de mani\u00e8re tr\u00e8s simple.<\/p>\n<\/div><\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n\r\n<div class=\"et_pb_section_10 et_pb_section et_section_regular et_flex_section\">\r\n<div class=\"et_pb_row_46 et_pb_row et_flex_row et_animated\">\r\n<div class=\"et_pb_column_60 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone et_flex_column_24_24_tabletWide\">\r\n<div class=\"et_pb_heading_35 et_pb_heading et_pb_module et_flex_module\"><div class=\"et_pb_heading_container\"><h2 class=\"et_pb_module_header\">S\u00e9curit\u00e9 et conformit\u00e9<\/h2><\/div><\/div>\r\n\r\n<div class=\"et_pb_accordion_3 et_pb_accordion et_pb_module et_flex_module\">\r\n<div class=\"et_pb_accordion_item_10 et_pb_accordion_item et_pb_toggle et_pb_module et_pb_toggle_open et_flex_module\"><h5 class=\"et_pb_toggle_title\">Y a-t-il des contre-indications \u00e0 l'utilisation des CEMP ? <\/h5><div class=\"et_pb_toggle_content et_flex_module\"><p>Bien que la technologie CEMP \u00e0 faible intensit\u00e9 puls\u00e9e soit extr\u00eamement s\u00fbre pour la plupart des gens, elle ne doit pas \u00eatre utilis\u00e9e par les personnes portant des implants \u00e9lectroniques (tels que des stimulateurs cardiaques ou des pompes \u00e0 insuline), les femmes enceintes, les b\u00e9b\u00e9s de moins de 2 semaines ou les personnes souffrant de troubles \u00e9pileptiques actifs (AVE). Dans ces cas, consultez toujours votre professionnel de sant\u00e9 si vous avez des pr\u00e9occupations sp\u00e9cifiques concernant votre sant\u00e9.<\/p>\n<\/div><\/div>\r\n\r\n<div class=\"et_pb_accordion_item_11 et_pb_accordion_item et_pb_toggle et_pb_module et_pb_toggle_close et_flex_module\"><h5 class=\"et_pb_toggle_title\">Le SmartPulser \u00e9met-il de la \u00ab pollution \u00e9lectromagn\u00e9tique \u00bb ?<\/h5><div class=\"et_pb_toggle_content et_flex_module\"><p>C'est tout le contraire. SmartPulser int\u00e8gre un g\u00e9n\u00e9rateur de fr\u00e9quence de pr\u00e9cision et fonctionne dans la gamme des fr\u00e9quences extr\u00eamement basses (ELF) non ionisantes (0,5\u201325 Hz), qui imite la nature. Notre technologie est con\u00e7ue pour cr\u00e9er un environnement magn\u00e9tique \u00ab propre \u00bb qui aide \u00e0 neutraliser les signaux chaotiques \u00e0 haute fr\u00e9quence pr\u00e9sents dans les foyers modernes (Wi-Fi, 5G, etc.).<\/p>\n<\/div><\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>","protected":false},"excerpt":{"rendered":"<p>D\u00e9couvrez le premier syst\u00e8me PEMF au monde, dot\u00e9 de la technologie r\u00e9volutionnaire \u00ab Inductive Fiber Coil \u00bb et \u00e9quip\u00e9 d&rsquo;une interface de commande \u00e0 \u00e9cran tactile extr\u00eamement conviviale.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-222911","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/soulspiritsaltspa.smartpulser.com\/fr\/wp-json\/wp\/v2\/pages\/222911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soulspiritsaltspa.smartpulser.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/soulspiritsaltspa.smartpulser.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/soulspiritsaltspa.smartpulser.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/soulspiritsaltspa.smartpulser.com\/fr\/wp-json\/wp\/v2\/comments?post=222911"}],"version-history":[{"count":12,"href":"https:\/\/soulspiritsaltspa.smartpulser.com\/fr\/wp-json\/wp\/v2\/pages\/222911\/revisions"}],"predecessor-version":[{"id":223294,"href":"https:\/\/soulspiritsaltspa.smartpulser.com\/fr\/wp-json\/wp\/v2\/pages\/222911\/revisions\/223294"}],"wp:attachment":[{"href":"https:\/\/soulspiritsaltspa.smartpulser.com\/fr\/wp-json\/wp\/v2\/media?parent=222911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}